{"id":15763,"date":"2018-05-09T13:00:23","date_gmt":"2018-05-09T12:00:23","guid":{"rendered":"https:\/\/www.inovallee.com\/?p=15763"},"modified":"2018-05-09T13:00:23","modified_gmt":"2018-05-09T12:00:23","slug":"viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels","status":"publish","type":"post","link":"http:\/\/www.inovallee.com\/en\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\/","title":{"rendered":"Viva Technology 2018 : la solution de vid\u00e9o automatique RoCamRoll s\u00e9lectionn\u00e9e par ACCORHOTELS dans le cadre de 2 challenges"},"content":{"rendered":"<p><strong><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-15767\" src=\"https:\/\/www.inovallee.com\/wp-content\/uploads\/2018\/05\/viva-tech.png\" alt=\"\" width=\"560\" height=\"292\" srcset=\"https:\/\/www.inovallee.com\/wp-content\/uploads\/2018\/05\/viva-tech.png 560w, https:\/\/www.inovallee.com\/wp-content\/uploads\/2018\/05\/viva-tech-300x156.png 300w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/>Choisi parmi plus de 300 candidats<\/strong><strong>, RoCamRoll fait partie des 32 startups<\/strong><strong> qui exposeront sur le AccorHotels\u00a0Lab, \u00e0 l\u2019occasion de la troisi\u00e8me \u00e9dition de Viva Technology, organis\u00e9e par Publicis et les Echos. Viva Technology, dont AccorHotels est partenaire, devrait accueillir cette ann\u00e9e encore pr\u00e8s de 70 000 visiteurs et 6 000 startups, aux c\u00f4t\u00e9s des meilleurs investisseurs mondiaux et leaders technologiques. Une formidable opportunit\u00e9 pour la startup du Tarmac de d\u00e9montrer le potentiel de sa solution de vid\u00e9o automatique RoCamRoll qui contribue \u00e0 inventer les \u00e9v\u00e9nements professionnels de demain.<\/strong><br \/>\nExposer sur le Lab des grands groupes pr\u00e9sents sur Viva Technology est le r\u00eave de toutes startups issues du monde de l\u2019innovation. C&rsquo;est en effet un lieu o\u00f9 se m\u00ealent collaboration et open innovation, un espace de rencontre entre startups et grands groupes leaders dans leur secteur. C\u2019est ainsi que plus de 300 startups ont postul\u00e9 aux challenges lanc\u00e9s par AccorHotels, parmi lesquels une trentaine aura l\u2019opportunit\u00e9 d\u2019exposer sur le AccorHotels Lab, vitrine de la strat\u00e9gie d\u2019innovation de ce leader mondial dans le domaine du voyage et du lifestyle. Pour capter l\u2019attention d\u2019AccorHotels, RoCamRoll a mis en avant les atouts de son syst\u00e8me de r\u00e9alisation vid\u00e9o automatique.<\/p>\n<h4><span style=\"color: #008000;\">Comment r\u00e9inventer les \u00e9v\u00e9nements professionnels et cr\u00e9er de la valeur pour la cha\u00eene h\u00f4teli\u00e8re ?<\/span><\/h4>\n<p><a href=\"https:\/\/challenges.vivatechnology.com\/en\/challenges\/accor-hotels\/pages\/accor-hotels-challenges?lang=en#challenge2\">AccorHotels<\/a> est le premier groupe h\u00f4telier fran\u00e7ais, implant\u00e9 dans 100 pays, avec pr\u00e8s de 4300 h\u00f4tels, resorts et r\u00e9sidences, mais aussi plus de 10 000 r\u00e9sidences priv\u00e9es d\u2019exception dans le monde entier. Parmi les 4 challenges propos\u00e9s, RoCamRoll a choisi de r\u00e9pondre aux challenges \u00ab<strong>\u00a0Reinvent Meetings &amp; Events in hotels \u00bb et \u00ab\u00a0The international scalability of local events in the hotel\u00a0\u00bb.<\/strong><br \/>\nRoCamRoll propose en effet un service innovant pour la partie h\u00e9bergement d\u2019\u00e9v\u00e9nements professionnels\u00a0: mettre \u00e0 la disposition des clients du groupe h\u00f4telier un syst\u00e8me de r\u00e9alisation vid\u00e9o complet, pour filmer leurs s\u00e9minaires, conf\u00e9rences ou salons \u00e0 l\u2018aide de <strong>cam\u00e9ras intelligentes, capables de d\u00e9tecter les mouvements des speakers, adoss\u00e9es \u00e0 une solution de montage automatique<\/strong>, int\u00e9grant des changements de plans, les slides, vid\u00e9os, notes \u00e9crites sur un tableau blanc, etc. Plus besoin de faire appel \u00e0 des professionnels de la vid\u00e9o, ce qui g\u00e9n\u00e8re de la valeur sur tous les plans\u00a0:<\/p>\n<ul>\n<li><strong>gain de co\u00fbts<\/strong> (la solution RoCamRoll ne n\u00e9cessite aucune connaissance technique, donc pas besoin de faire appel \u00e0 un vid\u00e9aste professionnel),<\/li>\n<li><strong>gain de temps<\/strong> (le film est livr\u00e9 moins de 5 minutes apr\u00e8s la fin de l\u2019\u00e9v\u00e9nement),<\/li>\n<li><strong>confidentialit\u00e9<\/strong> (le client est autonome pour la captation et le montage de son \u00e9v\u00e9nement, ce qui lui permet de garantir la confidentialit\u00e9 de ses CODIRS ou \u00e9v\u00e9nements internes).<\/li>\n<\/ul>\n<h4><span style=\"color: #008000;\">RoCamRoll offre une exp\u00e9rience personnalis\u00e9e et interactive pour les voyages d\u2019affaires<\/span><\/h4>\n<p><strong><img decoding=\"async\" class=\"alignleft wp-image-13429\" src=\"https:\/\/www.inovallee.com\/wp-content\/uploads\/rocamroll-regie-intelligente-Grenoble-INP-600x900.png\" alt=\"\" width=\"282\" height=\"423\" \/><\/strong>Avec son syst\u00e8me de vid\u00e9o intelligent, RoCamRoll g\u00e9n\u00e8re de la valeur sur le <strong>march\u00e9 des voyages d\u2019affaires et des \u00e9v\u00e9nements professionnels en personnalisant l\u2019exp\u00e9rience client<\/strong>\u00a0: \u00ab\u00a0Aujourd&rsquo;hui, les clients veulent des exp\u00e9riences uniques et interactives\u00a0\u00bb, explique Thierry Cravoisier, co-fondateur de RoCamRoll. \u00ab\u00a0Ils veulent plus qu\u2019une simple salle de r\u00e9union pour leurs conf\u00e9rences et s\u00e9minaires, ils attendent de vivre une exp\u00e9rience immersive, en temps r\u00e9el&#8230; Gr\u00e2ce \u00e0 sa <strong>plateforme d\u2019\u00e9dition d\u00e9di\u00e9e,<\/strong> RoCamRoll se positionne sur ce cr\u00e9neau en offrant aux clients la possibilit\u00e9 de <strong>personnaliser le film de leur \u00e9v\u00e9nement avec leur charte graphique <\/strong>(int\u00e9gration automatique de logos, jingles de d\u00e9but et de fin, sous-titrages, etc.). Le voyageur d\u2019affaires am\u00e9liore ainsi son exp\u00e9rience \u00e9v\u00e9nementielle car il repart avec le film mont\u00e9 de son meeting, copi\u00e9 sur une cl\u00e9 USB moins de cinq minutes apr\u00e8s la fin de l\u2019\u00e9v\u00e9nement\u00a0! Un beau souvenir qui permet de <strong>capitaliser sur chaque \u00e9v\u00e9nement et de valoriser l\u2019image de l\u2019entreprise<\/strong>.<\/p>\n<h4><span style=\"color: #008000;\">Elargir l\u2019audience de ses \u00e9v\u00e9nements professionnels et locaux \u00e0 l\u2019international<\/span><\/h4>\n<p>En outre, RoCamRoll offre aux organisateurs d\u2019\u00e9v\u00e9nements professionnels la possibilit\u00e9 de <strong>diffuser leurs \u00e9v\u00e9nements<\/strong> <strong>en streaming<\/strong>, c\u2019est-\u00e0-dire de retransmettre la vid\u00e9o en temps r\u00e9el \u00e0 des participants qui n\u2019auraient pas pu se d\u00e9placer. Ce qui leur permet d\u2019\u00e9tendre leur audience au niveau international et d\u2019augmenter l\u2019engagement de leurs collaborateurs, tout en r\u00e9duisant le nombre de d\u00e9placements.<\/p>\n<h4><span style=\"color: #008000;\">Une solution nomade, capable d\u2019\u00e9quiper et de valoriser tous les espaces h\u00f4teliers<\/span><\/h4>\n<p>La solution de vid\u00e9o automatis\u00e9e RoCamRoll pourrait permettre aux h\u00e9bergeurs d\u2019\u00e9v\u00e9nements d\u2019<strong>exploiter tous leurs espaces \u00e0 g\u00e9om\u00e9trie variable et de valoriser les salles p\u00e9riph\u00e9riques<\/strong>\u00a0: nomade et Plug &amp; play, le syst\u00e8me RoCamRoll est conditionn\u00e9 dans deux valises, faciles \u00e0 manier et \u00e0 transporter.<\/p>\n<h5>Pour d\u00e9couvrir tous les atouts de la solution <strong>RoCamRoll\u00a0<\/strong>, r\u00e9servez d\u00e8s maintenant vos billets pour Viva Technology et venez rencontrer l\u2019\u00e9quipe sur le <strong>LAB AccorHotels Hall 1<\/strong>, stand <strong>J41-005. Au programme, de nombreuses d\u00e9mos\u00a0: pitchs de startups, interviews de personnalit\u00e9s\u2026 le tout film\u00e9 et mont\u00e9 en direct live <\/strong>!<\/h5>","protected":false},"excerpt":{"rendered":"<p>Choisi parmi plus de 300 candidats, RoCamRoll fait partie des 32 startups qui exposeront sur le AccorHotels\u00a0Lab, \u00e0 l\u2019occasion de la troisi\u00e8me \u00e9dition de Viva Technology, organis\u00e9e par Publicis et les Echos. Viva Technology, dont AccorHotels est partenaire, devrait accueillir cette ann\u00e9e encore pr\u00e8s de 70 000 visiteurs et 6 000 startups, aux c\u00f4t\u00e9s des [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":15769,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45,44],"tags":[],"class_list":["post-15763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-startup-tarmac","category-tarmac-incubator"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Viva Technology 2018 : la solution de vid\u00e9o automatique RoCamRoll s\u00e9lectionn\u00e9e par ACCORHOTELS dans le cadre de 2 challenges - inovall\u00e9e<\/title>\n<meta name=\"description\" content=\"Choisi parmi plus de 300 candidats, la solution de vid\u00e9o automatique RoCamRoll fait partie des 32 startups qui exposeront sur le AccorHotels Lab, \u00e0 l\u2019occasion de Viva Technology.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.inovallee.com\/en\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viva Technology 2018 : la solution de vid\u00e9o automatique RoCamRoll s\u00e9lectionn\u00e9e par ACCORHOTELS dans le cadre de 2 challenges - inovall\u00e9e\" \/>\n<meta property=\"og:description\" content=\"Choisi parmi plus de 300 candidats, la solution de vid\u00e9o automatique RoCamRoll fait partie des 32 startups qui exposeront sur le AccorHotels Lab, \u00e0 l\u2019occasion de Viva Technology.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.inovallee.com\/en\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\/\" \/>\n<meta property=\"og:site_name\" content=\"inovall\u00e9e\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/technopoleinovallee\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-09T12:00:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.inovallee.com\/wp-content\/uploads\/2018\/05\/rocamroll-vivatech.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Inovallee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@inovallee\" \/>\n<meta name=\"twitter:site\" content=\"@inovallee\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Inovallee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\\\/\"},\"author\":{\"name\":\"Inovallee\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#\\\/schema\\\/person\\\/a45b15518aad3111b2d61d257a3e023b\"},\"headline\":\"Viva Technology 2018 : la solution de vid\u00e9o automatique RoCamRoll s\u00e9lectionn\u00e9e par ACCORHOTELS dans le cadre de 2 challenges\",\"datePublished\":\"2018-05-09T12:00:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\\\/\"},\"wordCount\":892,\"publisher\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.inovallee.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/rocamroll-vivatech.jpg\",\"articleSection\":[\"L'\u00e9cho des startups du Tarmac\",\"Tarmac incubator\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\\\/\",\"url\":\"https:\\\/\\\/www.inovallee.com\\\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\\\/\",\"name\":\"Viva Technology 2018 : la solution de vid\u00e9o automatique RoCamRoll s\u00e9lectionn\u00e9e par ACCORHOTELS dans le cadre de 2 challenges - inovall\u00e9e\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.inovallee.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/rocamroll-vivatech.jpg\",\"datePublished\":\"2018-05-09T12:00:23+00:00\",\"description\":\"Choisi parmi plus de 300 candidats, la solution de vid\u00e9o automatique RoCamRoll fait partie des 32 startups qui exposeront sur le AccorHotels Lab, \u00e0 l\u2019occasion de Viva Technology.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.inovallee.com\\\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.inovallee.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/rocamroll-vivatech.jpg\",\"contentUrl\":\"https:\\\/\\\/www.inovallee.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/rocamroll-vivatech.jpg\",\"width\":900,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.inovallee.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viva Technology 2018 : la solution de vid\u00e9o automatique RoCamRoll s\u00e9lectionn\u00e9e par ACCORHOTELS dans le cadre de 2 challenges\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#website\",\"url\":\"https:\\\/\\\/www.inovallee.com\\\/\",\"name\":\"inovall\u00e9e technopole, Home to software & smart technologies\",\"description\":\"Home to software &amp; smart technologies\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.inovallee.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#organization\",\"name\":\"inovall\u00e9e\",\"url\":\"https:\\\/\\\/www.inovallee.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.inovallee.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/inovallee_2022_GrenobleAlpes.png\",\"contentUrl\":\"https:\\\/\\\/www.inovallee.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/inovallee_2022_GrenobleAlpes.png\",\"width\":945,\"height\":369,\"caption\":\"inovall\u00e9e\"},\"image\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/technopoleinovallee\\\/\",\"https:\\\/\\\/x.com\\\/inovallee\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/inovall-e\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/inovallee?reload=9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#\\\/schema\\\/person\\\/a45b15518aad3111b2d61d257a3e023b\",\"name\":\"Inovallee\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viva Technology 2018 : la solution de vid\u00e9o automatique RoCamRoll s\u00e9lectionn\u00e9e par ACCORHOTELS dans le cadre de 2 challenges - inovall\u00e9e","description":"Choisi parmi plus de 300 candidats, la solution de vid\u00e9o automatique RoCamRoll fait partie des 32 startups qui exposeront sur le AccorHotels Lab, \u00e0 l\u2019occasion de Viva Technology.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.inovallee.com\/en\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\/","og_locale":"en_GB","og_type":"article","og_title":"Viva Technology 2018 : la solution de vid\u00e9o automatique RoCamRoll s\u00e9lectionn\u00e9e par ACCORHOTELS dans le cadre de 2 challenges - inovall\u00e9e","og_description":"Choisi parmi plus de 300 candidats, la solution de vid\u00e9o automatique RoCamRoll fait partie des 32 startups qui exposeront sur le AccorHotels Lab, \u00e0 l\u2019occasion de Viva Technology.","og_url":"https:\/\/www.inovallee.com\/en\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\/","og_site_name":"inovall\u00e9e","article_publisher":"https:\/\/www.facebook.com\/technopoleinovallee\/","article_published_time":"2018-05-09T12:00:23+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/www.inovallee.com\/wp-content\/uploads\/2018\/05\/rocamroll-vivatech.jpg","type":"image\/jpeg"}],"author":"Inovallee","twitter_card":"summary_large_image","twitter_creator":"@inovallee","twitter_site":"@inovallee","twitter_misc":{"Written by":"Inovallee","Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.inovallee.com\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\/#article","isPartOf":{"@id":"https:\/\/www.inovallee.com\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\/"},"author":{"name":"Inovallee","@id":"https:\/\/www.inovallee.com\/#\/schema\/person\/a45b15518aad3111b2d61d257a3e023b"},"headline":"Viva Technology 2018 : la solution de vid\u00e9o automatique RoCamRoll s\u00e9lectionn\u00e9e par ACCORHOTELS dans le cadre de 2 challenges","datePublished":"2018-05-09T12:00:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.inovallee.com\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\/"},"wordCount":892,"publisher":{"@id":"https:\/\/www.inovallee.com\/#organization"},"image":{"@id":"https:\/\/www.inovallee.com\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\/#primaryimage"},"thumbnailUrl":"https:\/\/www.inovallee.com\/wp-content\/uploads\/2018\/05\/rocamroll-vivatech.jpg","articleSection":["L'\u00e9cho des startups du Tarmac","Tarmac incubator"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.inovallee.com\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\/","url":"https:\/\/www.inovallee.com\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\/","name":"Viva Technology 2018 : la solution de vid\u00e9o automatique RoCamRoll s\u00e9lectionn\u00e9e par ACCORHOTELS dans le cadre de 2 challenges - inovall\u00e9e","isPartOf":{"@id":"https:\/\/www.inovallee.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.inovallee.com\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\/#primaryimage"},"image":{"@id":"https:\/\/www.inovallee.com\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\/#primaryimage"},"thumbnailUrl":"https:\/\/www.inovallee.com\/wp-content\/uploads\/2018\/05\/rocamroll-vivatech.jpg","datePublished":"2018-05-09T12:00:23+00:00","description":"Choisi parmi plus de 300 candidats, la solution de vid\u00e9o automatique RoCamRoll fait partie des 32 startups qui exposeront sur le AccorHotels Lab, \u00e0 l\u2019occasion de Viva Technology.","breadcrumb":{"@id":"https:\/\/www.inovallee.com\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.inovallee.com\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.inovallee.com\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\/#primaryimage","url":"https:\/\/www.inovallee.com\/wp-content\/uploads\/2018\/05\/rocamroll-vivatech.jpg","contentUrl":"https:\/\/www.inovallee.com\/wp-content\/uploads\/2018\/05\/rocamroll-vivatech.jpg","width":900,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.inovallee.com\/viva-technology-la-solution-de-video-automatique-rocamroll-selectionnee-par-accorhotels\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.inovallee.com\/"},{"@type":"ListItem","position":2,"name":"Viva Technology 2018 : la solution de vid\u00e9o automatique RoCamRoll s\u00e9lectionn\u00e9e par ACCORHOTELS dans le cadre de 2 challenges"}]},{"@type":"WebSite","@id":"https:\/\/www.inovallee.com\/#website","url":"https:\/\/www.inovallee.com\/","name":"inovall\u00e9e technopole, Home to software & smart technologies","description":"Home to software &amp; smart technologies","publisher":{"@id":"https:\/\/www.inovallee.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inovallee.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.inovallee.com\/#organization","name":"inovall\u00e9e","url":"https:\/\/www.inovallee.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.inovallee.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.inovallee.com\/wp-content\/uploads\/2023\/08\/inovallee_2022_GrenobleAlpes.png","contentUrl":"https:\/\/www.inovallee.com\/wp-content\/uploads\/2023\/08\/inovallee_2022_GrenobleAlpes.png","width":945,"height":369,"caption":"inovall\u00e9e"},"image":{"@id":"https:\/\/www.inovallee.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/technopoleinovallee\/","https:\/\/x.com\/inovallee","https:\/\/www.linkedin.com\/company\/inovall-e\/","https:\/\/www.youtube.com\/user\/inovallee?reload=9"]},{"@type":"Person","@id":"https:\/\/www.inovallee.com\/#\/schema\/person\/a45b15518aad3111b2d61d257a3e023b","name":"Inovallee"}]}},"_links":{"self":[{"href":"http:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/posts\/15763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/comments?post=15763"}],"version-history":[{"count":0,"href":"http:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/posts\/15763\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/media\/15769"}],"wp:attachment":[{"href":"http:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/media?parent=15763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/categories?post=15763"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/tags?post=15763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}