{"id":75,"count":45,"description":"","link":"https:\/\/www.inovallee.com\/en\/category\/tarmac-incubator\/start-up-inovallee\/","name":"L'\u00e9cho des start-up d'inovall\u00e9e","slug":"start-up-inovallee","taxonomy":"category","parent":44,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des L&#039;\u00e9cho des start-up d&#039;inovall\u00e9e - inovall\u00e9e<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.inovallee.com\/en\/category\/tarmac-incubator\/start-up-inovallee\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des L&#039;\u00e9cho des start-up d&#039;inovall\u00e9e - inovall\u00e9e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.inovallee.com\/en\/category\/tarmac-incubator\/start-up-inovallee\/\" \/>\n<meta property=\"og:site_name\" content=\"inovall\u00e9e\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@inovallee\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/category\\\/tarmac-incubator\\\/start-up-inovallee\\\/\",\"url\":\"https:\\\/\\\/www.inovallee.com\\\/category\\\/tarmac-incubator\\\/start-up-inovallee\\\/\",\"name\":\"Archives des L'\u00e9cho des start-up d'inovall\u00e9e - inovall\u00e9e\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/category\\\/tarmac-incubator\\\/start-up-inovallee\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/category\\\/tarmac-incubator\\\/start-up-inovallee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.inovallee.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tarmac incubator\",\"item\":\"https:\\\/\\\/www.inovallee.com\\\/category\\\/tarmac-incubator\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L'\u00e9cho des start-up d'inovall\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#website\",\"url\":\"https:\\\/\\\/www.inovallee.com\\\/\",\"name\":\"inovall\u00e9e technopole, Home to software & smart technologies\",\"description\":\"Home to software &amp; smart technologies\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.inovallee.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#organization\",\"name\":\"inovall\u00e9e\",\"url\":\"https:\\\/\\\/www.inovallee.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.inovallee.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/inovallee_2022_GrenobleAlpes.png\",\"contentUrl\":\"https:\\\/\\\/www.inovallee.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/inovallee_2022_GrenobleAlpes.png\",\"width\":945,\"height\":369,\"caption\":\"inovall\u00e9e\"},\"image\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/technopoleinovallee\\\/\",\"https:\\\/\\\/x.com\\\/inovallee\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/inovall-e\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/inovallee?reload=9\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des L'\u00e9cho des start-up d'inovall\u00e9e - inovall\u00e9e","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.inovallee.com\/en\/category\/tarmac-incubator\/start-up-inovallee\/","og_locale":"en_GB","og_type":"article","og_title":"Archives des L'\u00e9cho des start-up d'inovall\u00e9e - inovall\u00e9e","og_url":"https:\/\/www.inovallee.com\/en\/category\/tarmac-incubator\/start-up-inovallee\/","og_site_name":"inovall\u00e9e","twitter_card":"summary_large_image","twitter_site":"@inovallee","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.inovallee.com\/category\/tarmac-incubator\/start-up-inovallee\/","url":"https:\/\/www.inovallee.com\/category\/tarmac-incubator\/start-up-inovallee\/","name":"Archives des L'\u00e9cho des start-up d'inovall\u00e9e - inovall\u00e9e","isPartOf":{"@id":"https:\/\/www.inovallee.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.inovallee.com\/category\/tarmac-incubator\/start-up-inovallee\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.inovallee.com\/category\/tarmac-incubator\/start-up-inovallee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.inovallee.com\/"},{"@type":"ListItem","position":2,"name":"Tarmac incubator","item":"https:\/\/www.inovallee.com\/category\/tarmac-incubator\/"},{"@type":"ListItem","position":3,"name":"L'\u00e9cho des start-up d'inovall\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/www.inovallee.com\/#website","url":"https:\/\/www.inovallee.com\/","name":"inovall\u00e9e technopole, Home to software & smart technologies","description":"Home to software &amp; smart technologies","publisher":{"@id":"https:\/\/www.inovallee.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inovallee.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.inovallee.com\/#organization","name":"inovall\u00e9e","url":"https:\/\/www.inovallee.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.inovallee.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.inovallee.com\/wp-content\/uploads\/2023\/08\/inovallee_2022_GrenobleAlpes.png","contentUrl":"https:\/\/www.inovallee.com\/wp-content\/uploads\/2023\/08\/inovallee_2022_GrenobleAlpes.png","width":945,"height":369,"caption":"inovall\u00e9e"},"image":{"@id":"https:\/\/www.inovallee.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/technopoleinovallee\/","https:\/\/x.com\/inovallee","https:\/\/www.linkedin.com\/company\/inovall-e\/","https:\/\/www.youtube.com\/user\/inovallee?reload=9"]}]}},"_links":{"self":[{"href":"https:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/categories\/75","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/categories\/44"}],"wp:post_type":[{"href":"https:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/posts?categories=75"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}