{"id":24919,"date":"2020-04-13T22:46:08","date_gmt":"2020-04-13T20:46:08","guid":{"rendered":"https:\/\/www.inovallee.com\/?p=24919"},"modified":"2022-01-04T11:08:51","modified_gmt":"2022-01-04T10:08:51","slug":"nxp-investit-dans-kalray","status":"publish","type":"post","link":"https:\/\/www.inovallee.com\/en\/nxp-investit-dans-kalray\/","title":{"rendered":"NXP investit 8 millions d&#039;euros dans Kalray pour acc\u00e9l\u00e9rer le cod\u00e9veloppement de solutions pour les v\u00e9hicules autonomes"},"content":{"rendered":"<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.inovallee.com\/wp-content\/uploads\/autonomous_vehicle_kalray.png\" alt=\"\" class=\"wp-image-24920\" width=\"551\" height=\"368\"\/><figcaption><strong>\u00a9<\/strong> Kalray<\/figcaption><\/figure><\/div>\n\n\n<p><strong>La soci\u00e9t\u00e9 Kalray, pionni\u00e8re\ndes processeurs \u00ab&nbsp;manycoeurs \u00bb pour les nouveaux syst\u00e8mes intelligents bas\u00e9e\nsur inovall\u00e9e, a annonc\u00e9 le 2 avril dernier un investissement strat\u00e9gique de <a href=\"https:\/\/www.nxp.com\/\">NXP Semiconductors<\/a>, leader mondial des\nsolutions de connectivit\u00e9 s\u00e9curis\u00e9e pour les applications embarqu\u00e9es&nbsp;: 8\nmillions d&rsquo;euros de prise de participation pour renforcer le partenariat entre\nles deux entreprises. L\u2019objectif&nbsp;: combiner les atouts des solutions NXP\nAutomotive et des processeurs intelligents Kalray MPPA\u00ae (Massively Parallel\nProcessor Array) afin de cod\u00e9velopper, promouvoir et d\u00e9ployer des solutions conjointes\nsur le march\u00e9 de la conduite autonome.<\/strong><\/p>\n\n\n<p>\u00ab <em>L\u2019investissement sera r\u00e9alis\u00e9 par l\u2019\u00e9mission r\u00e9serv\u00e9e\nau b\u00e9n\u00e9fice de NXP BV, soci\u00e9t\u00e9 du groupe NXP, de 503 461 actions ordinaires\navec suppression du droit pr\u00e9f\u00e9rentiel de souscription des actionnaires de la\nSoci\u00e9t\u00e9. \u00c0 la suite du r\u00e8glement-livraison des Actions Nouvelles, le groupe NXP\nd\u00e9tiendra environ 9,95 % du capital de Kalray et de ses droits de vote<\/em> \u00bb,\nexplique Kalray dans son Communiqu\u00e9 de presse. Kalray pr\u00e9sentera \u00e9galement au\nvote de la prochaine assembl\u00e9e g\u00e9n\u00e9rale une r\u00e9solution relative \u00e0 la\nd\u00e9signation de Sean Pitonak, Senior Vice President, Corporate Development et\nM&amp;A de NXP, en qualit\u00e9 de membre du conseil de surveillance. <\/p>\n\n\n<p>Cette transaction vise \u00e0 renforcer le partenariat entre NXP\net Kalray, annonc\u00e9 il y a un an au CES 2019, afin de d\u00e9velopper et d\u00e9ployer une\nplateforme mat\u00e9rielle et logicielle commune, s\u00fbre, fiable et \u00e9volutive pour\nv\u00e9hicules autonomes, allant du niveau L2 (autonomie partielle) au L5 (autonomie\ncompl\u00e8te). L&rsquo;arriv\u00e9e de NXP, le sp\u00e9cialiste des semi-conducteurs, \u00e0 son capital\nconforte la startup dans sa strat\u00e9gie de d\u00e9veloppement concernant les solutions\ndans l\u2019automobile et les syst\u00e8mes embarqu\u00e9s. <\/p>\n\n\n<h2 class=\"wp-block-heading\">Un investissement strat\u00e9gique et un partenariat \u00e0 long terme<\/h2>\n\n\n<p>\u00ab <em>Nous sommes fiers d&rsquo;annoncer que NXP est d\u00e9sormais l&rsquo;un\nde nos investisseurs strat\u00e9giques<\/em>&nbsp;\u00bb, commente Eric Baissus, Pr\u00e9sident\ndu Directoire de Kalray. \u00ab&nbsp;<em>Cette prise de participation vient en\ncontinuation de notre collaboration sur le v\u00e9hicule du futur<\/em>. <em>Cela fait\nun an que nous travaillons sur la conjonction de nos offres pour un d\u00e9ploiement\nsur le march\u00e9 mondial<\/em>.&nbsp;<em>NXP est l&rsquo;une des soci\u00e9t\u00e9s les mieux\n\u00e9tablies et les plus expertes dans le domaine des semi-conducteurs pour\nl\u2019industrie automobile. Cet investissement va renforcer la collaboration entre\nnos \u00e9quipes et participera au financement de notre feuille de route sur le\nsegment automobile. Je suis convaincu que nous avons une solution commune\nunique et ouverte \u00e0 proposer au march\u00e9, pour une conduite autonome fiable,\nalliant performances et s\u00e9curit\u00e9.<\/em>&nbsp;\u00bb<\/p>\n\n\n<p>NXP et Kalray affirment\nainsi leur volont\u00e9 de proposer au march\u00e9 automobile une solution int\u00e9gr\u00e9e et\n\u00e9volutive, comprenant le processeur principal, l\u2019acc\u00e9l\u00e9ration de l\u2019IA et des\nr\u00e9seaux neuronaux, des capacit\u00e9s de s\u00e9curit\u00e9 fonctionnelle et des outils\noptimis\u00e9s. Une solution qui leur permettra ainsi d\u2019adresser conjointement\nl\u2019ensemble des exigences n\u00e9cessaires pour des solutions ADAS (<em>Advanced\nDriver-Assistance Systems<\/em>, ou syst\u00e8mes d\u2019aide \u00e0 la conduite automobile et\nde conduite autonome) de nouvelle g\u00e9n\u00e9ration. Les deux soci\u00e9t\u00e9s entendent\n\u00e9galement renforcer leur collaboration pour r\u00e9pondre ensemble aux opportunit\u00e9s\ncommerciales. NXP apportera \u00e9galement un soutien \u00e0 Kalray en termes de ventes,\nmarketing, expertise automobile et support technique \u00e0 l\u2019\u00e9chelle mondiale. <\/p>\n\n\n<h2 class=\"wp-block-heading\">La prochaine g\u00e9n\u00e9ration de la plateforme de conduite autonome NXP BlueBox embarquera les processeurs intelligents de Kalray<\/h2>\n\n\n<p>La plateforme de conduite autonome NXP BlueBox, qui offre\nles performances, la s\u00e9curit\u00e9 fonctionnelle et la fiabilit\u00e9 requises pour d\u00e9velopper\ndes voitures autonomes, est actuellement bas\u00e9e sur la famille de processeurs\nautomobiles S32 et les processeurs Layerscape\u00ae. La prochaine g\u00e9n\u00e9ration de cette\nplateforme embarquera les processeurs intelligents MPPA\u00ae de Kalray et sera\npropos\u00e9e aux clients automobiles, ainsi qu\u2019\u00e0 l&rsquo;\u00e9cosyst\u00e8me NXP Bluebox.<\/p>\n\n\n<p>\u00ab <em>D\u00e9velopper une plateforme pour la conduite autonome,\nint\u00e9grant les performances requises en termes d\u2019IA et de tr\u00e8s hautes capacit\u00e9s\nde calcul, le tout avec un haut niveau de s\u00e9curit\u00e9, n\u00e9cessite une tr\u00e8s \u00e9troite\ncollaboration<\/em> \u00bb, d\u00e9clare Henri Ardevol, Senior Vice-Pr\u00e9sident et Directeur\nG\u00e9n\u00e9ral solutions automobiles chez NXP. \u00ab <em>Le savoir-faire de Kalray et sa\nplateforme ouverte et \u00e9volutive MPPA\u00ae, sont compl\u00e9mentaires \u00e0 l\u2019expertise de\nNXP et \u00e0 son portefeuille de solutions pour l\u2019automobile. Nous sommes tr\u00e8s\nheureux d\u2019associer notre exp\u00e9rience et nos efforts, afin d\u2019offrir \u00e0 nos clients\nla meilleure plateforme pour leur prochaine g\u00e9n\u00e9ration de v\u00e9hicules.<\/em> \u00bb<\/p>\n\n\n<h2 class=\"wp-block-heading\">La voiture totalement autonome, un futur proche&nbsp;?<\/h2>\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img decoding=\"async\" src=\"https:\/\/www.inovallee.com\/wp-content\/uploads\/MPPa-chip-in-Kalray-brain-273x300.png\" alt=\"\" class=\"wp-image-24921\"\/><\/figure><\/div>\n\n\n<p>Eric Baissus explicite par ailleurs les avantages de la technologie d\u00e9velopp\u00e9e par Kalray pour les solutions de conduite autonome\u00a0: \u00ab\u00a0<em>Dans une voiture, chaque nouvelle option vient avec un computer. On consid\u00e8re qu\u2019il y a entre 50 et 100 computers dans une seule voiture aujourd\u2019hui. Pour plus de s\u00e9curit\u00e9 et d\u2019autonomie, de nouvelles fonctions doivent \u00eatre ajout\u00e9es, comme par exemple d\u00e9tecter un pi\u00e9ton pour ralentir, s\u2019arr\u00eater \u00e0 un stop, etc. La voiture du futur a besoin d\u2019une puissance de calcul multipli\u00e9e par 100 ou par 1000, ce sont un peu des data center sur roues\u00a0! Par son architecture unique, le processeur de Kalray est multic\u0153urs et peut g\u00e9rer \u00e9norm\u00e9ment de fonctions en parall\u00e8le, tout en ajoutant de la vitesse de calcul<\/em>\u00a0\u00bb.<\/p>\n\n\n<p>Pourtant, dans l\u2019imaginaire collectif, la voiture 100% autonome, sans volant et sans chauffeur, reste per\u00e7ue comme un fantasme futuriste. Alors o\u00f9 en est-on r\u00e9ellement\u00a0? D\u2019apr\u00e8s Eric Baissus, \u00ab\u00a0<em>il reste encore beaucoup d\u2019\u00e9tapes \u00e0 franchir<\/em>\u00a0\u00bb avant d\u2019arriver \u00e0 un v\u00e9hicule de niveau L5, c\u2019est-\u00e0-dire enti\u00e8rement automatique. \u00ab\u00a0<em>L\u2019ordre de grandeur est plut\u00f4t \u00e0 horizon 2030 pour voir appara\u00eetre des voitures compl\u00e8tement autonomes. Les mod\u00e8les que l\u2019on peut trouver sur le march\u00e9 automobile actuellement sont de niveau L2 et des voitures L2+, c\u2019est-\u00e0-dire capables de prendre des virages et de s\u2019arr\u00eater, ne devraient pas tarder \u00e0 sortir<\/em> \u00bb<em>. <\/em><\/p>\n\n\n<p>Mais l\u2019industrie automobile en est d\u00e9j\u00e0 au niveau L3 (v\u00e9hicule capable de s\u2019arr\u00eater et de changer de voie) et les \u00e9quipes de R&amp;D de Kalray travaillent sur les niveaux L3, mais aussi L4 (v\u00e9hicule capable de doubler, changer de voie, s\u2019arr\u00eater aux p\u00e9ages\u2026)<em>. <\/em> \u00ab <em>Ce march\u00e9 est r\u00e9ellement enthousiasmant, m\u00eame s\u2019il s\u2019agit d\u2019un march\u00e9 \u00e0 long terme. Mais il n&rsquo;y a aucune raison technologique pour que le v\u00e9hicule autonome ne devienne pas r\u00e9alit\u00e9. C&rsquo;est un march\u00e9 qui va prendre du temps, qui est profond et il est important que Kalray se positionne d\u00e8s aujourd\u2019hui en tant que contributeur de valeur<\/em>\u00a0\u00bb. Pour rappel, Kalray adresse d\u2019ores et d\u00e9j\u00e0 un autre march\u00e9 cible, celui des <a href=\"\/en\/?p=23922\">data centers<\/a>, un march\u00e9 \u00e0 court terme, tr\u00e8s dynamique sur des verticaux en forte croissance.<\/p>\n\n\n<h2 class=\"wp-block-heading\">Kalray maintient ses activit\u00e9s pendant la crise Covid-19 et devrait pouvoir\ntenir sa roadmap technologique<\/h2>\n\n\n<p>Kalray, qui est peu d\u00e9pendante de ses fournisseurs, maintient\nses activit\u00e9s de recherche &amp; d\u00e9veloppement dans le contexte de l\u2019\u00e9pid\u00e9mie\nde Covid-19, avec l\u2019ensemble de ses \u00e9quipes de d\u00e9veloppement en t\u00e9l\u00e9travail\ndepuis l\u2019annonce du confinement le 16 mars, sans recours pour le moment au\nch\u00f4mage partiel. En l\u2019\u00e9tat des informations \u00e0 sa disposition, Kalray confirme \u00e9galement\nque son niveau de tr\u00e9sorerie actuel est solide (15,7 M\u20ac au 31 d\u00e9cembre 2019, renforc\u00e9e\npar l\u2019investissement de NXP), mais qu\u2019elle va prendre des pr\u00e9cautions suppl\u00e9mentaires\npour s\u00e9curiser cette tr\u00e9sorerie (sollicitation d\u2019emprunts bancaires, limitation\nde certains investissements\u2026).<\/p>\n\n\n<p>Elle devrait toutefois lui permettre de mettre en \u0153uvre sa\nroadmap technologique, y compris les d\u00e9veloppements li\u00e9s au partenariat\nstrat\u00e9gique NXP Kalray et son d\u00e9ploiement commercial, au cours des douze\nprochains mois. Les mesures de confinement mises en place dans de nombreux pays\nsont n\u00e9anmoins susceptibles de ralentir les cycles commerciaux, ce qui pourrait\nd\u00e9caler le d\u00e9ploiement de certains projets sur lesquels travaille la Soci\u00e9t\u00e9,\nqui commentera ses r\u00e9sultats 2019 le 20 avril prochain, conform\u00e9ment au\ncalendrier annonc\u00e9. Elle esp\u00e8re \u00eatre alors en mesure d\u2019apporter plus de\npr\u00e9cisions sur l\u2019impact sur son activit\u00e9 de la crise li\u00e9e \u00e0 l\u2019\u00e9pid\u00e9mie\nCovid-19. <\/p>","protected":false},"excerpt":{"rendered":"<p>La soci\u00e9t\u00e9 Kalray, pionni\u00e8re des processeurs \u00ab&nbsp;manycoeurs \u00bb pour les nouveaux syst\u00e8mes intelligents bas\u00e9e sur inovall\u00e9e, a annonc\u00e9 le 2 avril dernier un investissement strat\u00e9gique de NXP Semiconductors, leader mondial des solutions de connectivit\u00e9 s\u00e9curis\u00e9e pour les applications embarqu\u00e9es&nbsp;: 8 millions d&rsquo;euros de prise de participation pour renforcer le partenariat entre les deux entreprises. L\u2019objectif&nbsp;: [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":24920,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[75,28,29],"tags":[252,117,118],"class_list":["post-24919","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-start-up-inovallee","category-actus-entreprises","category-evenements","tag-kalray","tag-processeur","tag-voiture-autonome"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>V\u00e9hicules autonomes : NXP investit 8 millions d&#039;euros dans Kalray<\/title>\n<meta name=\"description\" content=\"NXP Semiconductors investit 8 millions d&#039;euros dans Kalray pour acc\u00e9l\u00e9rer le cod\u00e9veloppement de solutions pour les v\u00e9hicules autonomes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.inovallee.com\/en\/nxp-investit-dans-kalray\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"V\u00e9hicules autonomes : NXP investit 8 millions d&#039;euros dans Kalray\" \/>\n<meta property=\"og:description\" content=\"NXP Semiconductors investit 8 millions d&#039;euros dans Kalray pour acc\u00e9l\u00e9rer le cod\u00e9veloppement de solutions pour les v\u00e9hicules autonomes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.inovallee.com\/en\/nxp-investit-dans-kalray\/\" \/>\n<meta property=\"og:site_name\" content=\"inovall\u00e9e\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/technopoleinovallee\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-13T20:46:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-04T10:08:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.inovallee.com\/wp-content\/uploads\/2020\/04\/autonomous_vehicle_kalray.png\" \/>\n\t<meta property=\"og:image:width\" content=\"734\" \/>\n\t<meta property=\"og:image:height\" content=\"490\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Inovallee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@inovallee\" \/>\n<meta name=\"twitter:site\" content=\"@inovallee\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Inovallee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/nxp-investit-dans-kalray\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/nxp-investit-dans-kalray\\\/\"},\"author\":{\"name\":\"Inovallee\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#\\\/schema\\\/person\\\/a45b15518aad3111b2d61d257a3e023b\"},\"headline\":\"NXP investit 8 millions d&#039;euros dans Kalray pour acc\u00e9l\u00e9rer le cod\u00e9veloppement de solutions pour les v\u00e9hicules autonomes\",\"datePublished\":\"2020-04-13T20:46:08+00:00\",\"dateModified\":\"2022-01-04T10:08:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/nxp-investit-dans-kalray\\\/\"},\"wordCount\":1436,\"publisher\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/nxp-investit-dans-kalray\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.inovallee.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/autonomous_vehicle_kalray.png\",\"keywords\":[\"Kalray\",\"processeur\",\"Voiture autonome\"],\"articleSection\":[\"L'\u00e9cho des start-up d'inovall\u00e9e\",\"Sucess stories des entreprises d'inovall\u00e9e\",\"Technopole inovall\u00e9e\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/nxp-investit-dans-kalray\\\/\",\"url\":\"https:\\\/\\\/www.inovallee.com\\\/nxp-investit-dans-kalray\\\/\",\"name\":\"V\u00e9hicules autonomes : NXP investit 8 millions d'euros dans Kalray\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/nxp-investit-dans-kalray\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/nxp-investit-dans-kalray\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.inovallee.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/autonomous_vehicle_kalray.png\",\"datePublished\":\"2020-04-13T20:46:08+00:00\",\"dateModified\":\"2022-01-04T10:08:51+00:00\",\"description\":\"NXP Semiconductors investit 8 millions d'euros dans Kalray pour acc\u00e9l\u00e9rer le cod\u00e9veloppement de solutions pour les v\u00e9hicules autonomes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/nxp-investit-dans-kalray\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.inovallee.com\\\/nxp-investit-dans-kalray\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/nxp-investit-dans-kalray\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.inovallee.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/autonomous_vehicle_kalray.png\",\"contentUrl\":\"https:\\\/\\\/www.inovallee.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/autonomous_vehicle_kalray.png\",\"width\":734,\"height\":490,\"caption\":\"VEHICULE AUTONOME\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/nxp-investit-dans-kalray\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.inovallee.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NXP investit 8 millions d&#039;euros dans Kalray pour acc\u00e9l\u00e9rer le cod\u00e9veloppement de solutions pour les v\u00e9hicules autonomes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#website\",\"url\":\"https:\\\/\\\/www.inovallee.com\\\/\",\"name\":\"inovall\u00e9e technopole, Home to software & smart technologies\",\"description\":\"Home to software &amp; smart technologies\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.inovallee.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#organization\",\"name\":\"inovall\u00e9e\",\"url\":\"https:\\\/\\\/www.inovallee.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.inovallee.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/inovallee_2022_GrenobleAlpes.png\",\"contentUrl\":\"https:\\\/\\\/www.inovallee.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/inovallee_2022_GrenobleAlpes.png\",\"width\":945,\"height\":369,\"caption\":\"inovall\u00e9e\"},\"image\":{\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/technopoleinovallee\\\/\",\"https:\\\/\\\/x.com\\\/inovallee\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/inovall-e\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/inovallee?reload=9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.inovallee.com\\\/#\\\/schema\\\/person\\\/a45b15518aad3111b2d61d257a3e023b\",\"name\":\"Inovallee\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"V\u00e9hicules autonomes : NXP investit 8 millions d'euros dans Kalray","description":"NXP Semiconductors investit 8 millions d'euros dans Kalray pour acc\u00e9l\u00e9rer le cod\u00e9veloppement de solutions pour les v\u00e9hicules autonomes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.inovallee.com\/en\/nxp-investit-dans-kalray\/","og_locale":"en_GB","og_type":"article","og_title":"V\u00e9hicules autonomes : NXP investit 8 millions d'euros dans Kalray","og_description":"NXP Semiconductors investit 8 millions d'euros dans Kalray pour acc\u00e9l\u00e9rer le cod\u00e9veloppement de solutions pour les v\u00e9hicules autonomes.","og_url":"https:\/\/www.inovallee.com\/en\/nxp-investit-dans-kalray\/","og_site_name":"inovall\u00e9e","article_publisher":"https:\/\/www.facebook.com\/technopoleinovallee\/","article_published_time":"2020-04-13T20:46:08+00:00","article_modified_time":"2022-01-04T10:08:51+00:00","og_image":[{"width":734,"height":490,"url":"https:\/\/www.inovallee.com\/wp-content\/uploads\/2020\/04\/autonomous_vehicle_kalray.png","type":"image\/png"}],"author":"Inovallee","twitter_card":"summary_large_image","twitter_creator":"@inovallee","twitter_site":"@inovallee","twitter_misc":{"Written by":"Inovallee","Estimated reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.inovallee.com\/nxp-investit-dans-kalray\/#article","isPartOf":{"@id":"https:\/\/www.inovallee.com\/nxp-investit-dans-kalray\/"},"author":{"name":"Inovallee","@id":"https:\/\/www.inovallee.com\/#\/schema\/person\/a45b15518aad3111b2d61d257a3e023b"},"headline":"NXP investit 8 millions d&#039;euros dans Kalray pour acc\u00e9l\u00e9rer le cod\u00e9veloppement de solutions pour les v\u00e9hicules autonomes","datePublished":"2020-04-13T20:46:08+00:00","dateModified":"2022-01-04T10:08:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.inovallee.com\/nxp-investit-dans-kalray\/"},"wordCount":1436,"publisher":{"@id":"https:\/\/www.inovallee.com\/#organization"},"image":{"@id":"https:\/\/www.inovallee.com\/nxp-investit-dans-kalray\/#primaryimage"},"thumbnailUrl":"https:\/\/www.inovallee.com\/wp-content\/uploads\/2020\/04\/autonomous_vehicle_kalray.png","keywords":["Kalray","processeur","Voiture autonome"],"articleSection":["L'\u00e9cho des start-up d'inovall\u00e9e","Sucess stories des entreprises d'inovall\u00e9e","Technopole inovall\u00e9e"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.inovallee.com\/nxp-investit-dans-kalray\/","url":"https:\/\/www.inovallee.com\/nxp-investit-dans-kalray\/","name":"V\u00e9hicules autonomes : NXP investit 8 millions d'euros dans Kalray","isPartOf":{"@id":"https:\/\/www.inovallee.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.inovallee.com\/nxp-investit-dans-kalray\/#primaryimage"},"image":{"@id":"https:\/\/www.inovallee.com\/nxp-investit-dans-kalray\/#primaryimage"},"thumbnailUrl":"https:\/\/www.inovallee.com\/wp-content\/uploads\/2020\/04\/autonomous_vehicle_kalray.png","datePublished":"2020-04-13T20:46:08+00:00","dateModified":"2022-01-04T10:08:51+00:00","description":"NXP Semiconductors investit 8 millions d'euros dans Kalray pour acc\u00e9l\u00e9rer le cod\u00e9veloppement de solutions pour les v\u00e9hicules autonomes.","breadcrumb":{"@id":"https:\/\/www.inovallee.com\/nxp-investit-dans-kalray\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.inovallee.com\/nxp-investit-dans-kalray\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.inovallee.com\/nxp-investit-dans-kalray\/#primaryimage","url":"https:\/\/www.inovallee.com\/wp-content\/uploads\/2020\/04\/autonomous_vehicle_kalray.png","contentUrl":"https:\/\/www.inovallee.com\/wp-content\/uploads\/2020\/04\/autonomous_vehicle_kalray.png","width":734,"height":490,"caption":"VEHICULE AUTONOME"},{"@type":"BreadcrumbList","@id":"https:\/\/www.inovallee.com\/nxp-investit-dans-kalray\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.inovallee.com\/"},{"@type":"ListItem","position":2,"name":"NXP investit 8 millions d&#039;euros dans Kalray pour acc\u00e9l\u00e9rer le cod\u00e9veloppement de solutions pour les v\u00e9hicules autonomes"}]},{"@type":"WebSite","@id":"https:\/\/www.inovallee.com\/#website","url":"https:\/\/www.inovallee.com\/","name":"inovall\u00e9e technopole, Home to software & smart technologies","description":"Home to software &amp; smart technologies","publisher":{"@id":"https:\/\/www.inovallee.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inovallee.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.inovallee.com\/#organization","name":"inovall\u00e9e","url":"https:\/\/www.inovallee.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.inovallee.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.inovallee.com\/wp-content\/uploads\/2023\/08\/inovallee_2022_GrenobleAlpes.png","contentUrl":"https:\/\/www.inovallee.com\/wp-content\/uploads\/2023\/08\/inovallee_2022_GrenobleAlpes.png","width":945,"height":369,"caption":"inovall\u00e9e"},"image":{"@id":"https:\/\/www.inovallee.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/technopoleinovallee\/","https:\/\/x.com\/inovallee","https:\/\/www.linkedin.com\/company\/inovall-e\/","https:\/\/www.youtube.com\/user\/inovallee?reload=9"]},{"@type":"Person","@id":"https:\/\/www.inovallee.com\/#\/schema\/person\/a45b15518aad3111b2d61d257a3e023b","name":"Inovallee"}]}},"_links":{"self":[{"href":"https:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/posts\/24919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/comments?post=24919"}],"version-history":[{"count":0,"href":"https:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/posts\/24919\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/media\/24920"}],"wp:attachment":[{"href":"https:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/media?parent=24919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/categories?post=24919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovallee.com\/en\/wp-json\/wp\/v2\/tags?post=24919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}